{"id":54997,"date":"2021-03-03T08:48:42","date_gmt":"2021-03-03T07:48:42","guid":{"rendered":"http:\/\/www.abmnews.com\/blog\/?p=54997"},"modified":"2021-03-03T08:48:44","modified_gmt":"2021-03-03T07:48:44","slug":"alpine-f1-team-lancia-la-stagione-2021","status":"publish","type":"post","link":"https:\/\/www.abmnews.com\/blog\/alpine-f1-team-lancia-la-stagione-2021\/","title":{"rendered":"ALPINE F1 TEAM LANCIA LA STAGIONE 2021"},"content":{"rendered":"\n<p>Alpine F1 Team ha ufficialmente aperto una nuova era lanciando virtualmente la prima stagione della sua storia nel Campionato Mondiale FIA di Formula\u00a01.<\/p>\n<p>La monoposto di quest\u2019anno, denominata A521, indossa una stupenda livrea che abbina blu, bianco e rosso, sinonimo del patrimonio di Alpine nel mondo delle gare. L\u2019auto sar\u00e0 alimentata dal gruppo propulsore Renault E-Tech\u00a020B, un V6 da 1,6\u00a0l progettato e sviluppato a Viry-Ch\u00e2tillon, dove il costruttore francese vanta quarantacinque anni di attivit\u00e0 ininterrotta nella Formula 1.<\/p>\n<p>L\u2019A521 \u00e8 un\u2019evoluzione della R.S.20 che ha disputato la stagione\u00a02020. In linea con le modifiche al regolamento concordate l\u2019anno scorso durante la pandemia, i principali elementi strutturali dell\u2019A521 sono ripresi dall\u2019anno scorso. Tuttavia, tutti i componenti che non rientravano in quest\u2019ambito sono stati sviluppati e migliorati, soprattutto al posteriore, dove sono state imposte nuove restrizioni aerodinamiche dalla FIA.<\/p>\n<blockquote>\n<p><a><strong><em>Luca De Meo, Direttore Generale del Gruppo Renault: <\/em><\/strong><\/a><em>\u00c8 una vera gioia vedere il nome potente e vibrante di Alpine su una Formula\u00a01. Nuovi colori, una nuova Direzione, progetti ambiziosi: questo \u00e8 un nuovo inizio, basato su quarant\u2019anni di storia. Coniugheremo i valori dell\u2019autenticit\u00e0, dell\u2019eleganza e dell\u2019audacia di Alpine con la nostra competenza in termini di ingegneria e telaio. Questo \u00e8 il bello di essere un costruttore in Formula 1. Ci confronteremo con i nomi pi\u00f9 grandi in gare spettacolari, seguite da appassionati entusiasti. Non vedo l\u2019ora che inizi la stagione.<\/em><\/p>\n<\/blockquote>\n<p>La prima monoposto di Alpine\u00a0F1 Team sar\u00e0 affidata ad Esteban Ocon e Fernando Alonso. Dopo una pausa di due anni, Fernando torna alla Formula 1 in una scuderia con cui aveva vinto i suoi due titoli di Campione del Mondo di Formula 1 nel 2005 e 2006.<\/p>\n<p>Esteban, che inizia la sua seconda stagione con il team, vorr\u00e0 capitalizzare sui bei risultati del 2020, stagione in cui si \u00e8 aggiudicato il suo primo piazzamento sul podio in Formula 1 nel Gran Premio di Sakhir\u00a02020. Il ventiquattrenne francese affronta la sua quarta stagione completa nella disciplina dall\u2019esordio avvenuto ad Agosto 2016.<\/p>\n<p>Il team \u00e8 ora gestito da un nuovo trio preposto alla Direzione composta da Laurent Rossi, Direttore Generale di Alpine, Marcin Budkowski, Direttore Esecutivo, e Davide Brivio, Direttore di Gara. Pat Fry e R\u00e9mi Taffin si confermano, rispettivamente, Direttore Tecnico Telaio e Direttore Tecnico Motore.<\/p>\n<p>Membro di Alpine Academy, Guanyu Zhou continua a svolgere la funzione di pilota collaudatore del team, pur partecipando al Campionato FIA di Formula\u00a02 con UNI-Virtuosi.<\/p>\n<p>La prima F1 progettata da Alpine F1 Team effettuer\u00e0 i suoi primi giri in pista domani con Esteban Ocon in occasione di una giornata di riprese promozionali a Silverstone, due settimane prima delle prove prestagionali ufficiali sul Circuito Internazionale del Bahrain.<\/p>\n<blockquote>\n<p><strong>Laurent Rossi: <\/strong><em>Siamo orgogliosi di presentare oggi la primissima Formula\u00a01 di Alpine F1 Team per la stagione 2021. Si tratta di un passo importante per Alpine, che si posiziona come la Marca all\u2019avanguardia dell\u2019innovazione del Gruppo Renault. Alpine trova con naturalezza il suo posto negli alti standard, nel prestigio e nelle performance della Formula 1 ed \u00e8 con impazienza che attendiamo l\u2019esordio dell\u2019A521 con i nostri piloti, il due volte Campione del Mondo di Formula 1 Fernando Alonso ed Esteban Ocon. Quest\u2019anno, il nostro obiettivo \u00e8 chiaro: proseguire sulla scia dell\u2019anno scorso e combattere per conquistare piazzamenti sul podio. La nostra visione a lungo termine \u00e8 quella di vedere il nome Alpine sul gradino pi\u00f9 alto del podio in Formula 1. La competizione \u00e8 nel nostro DNA ed \u00e8 giunta l\u2019ora per i colori Alpine di ergersi fino all\u2019Olimpo del motorsport che \u00e8 la Formula\u00a01.<\/em><\/p>\n<\/blockquote>\n<blockquote>\n<p><strong>Esteban Ocon: <\/strong><em>Non vedo l\u2019ora di iniziare la stagione con l\u2019A521 nel Bahrain. L\u2019inverno \u00e8 stato, al tempo stesso, lungo e intenso, con molti preparativi. Io e il team siamo pronti per la nuova stagione. Adoro i nuovi colori Alpine e, come francese, sono orgoglioso che sulla mia monoposto ci sia la bandiera francese. Mi sento pi\u00f9 preparato dell\u2019anno scorso e penso che sia una cosa del tutto naturale, visto che sto per iniziare quest\u2019anno dopo una stagione completa nel 2020. Voglio cominciare trovandomi allo stesso livello in cui ero alla fine dell\u2019anno scorso e non c\u2019\u00e8 nessun motivo per cui non dovrebbe essere cos\u00ec. Sar\u00e0 fantastico lavorare con Fernando, un pilota che ammiro e una persona da cui traggo ispirazione da molto tempo. Non vedo l\u2019ora di collaborare con lui e di spingere in pista affinch\u00e9 il team raggiunga i suoi obiettivi.<\/em><\/p>\n<\/blockquote>\n<blockquote>\n<p><strong>Fernando Alonso: <\/strong><em>Sono molto contento di tornare alla Formula\u00a01 e di far parte del prossimo capitolo della storia di Alpine F1 Team nella disciplina. Ho lavorato sodo per la ripresa e l\u2019obiettivo \u00e8 di attaccare immediatamente. Prendere il volante della monoposto per la prima volta sar\u00e0 un momento entusiasmante e spero che entrambe le nostre sedi potranno godersi quel momento. Abbiamo un bel team e, con Esteban, dobbiamo proseguire gli sforzi dell\u2019anno scorso e ottenere buoni risultati. Sappiamo che la stagione si preannuncia estremamente competitiva, ma siamo pronti a raccogliere la sfida. L\u2019auto si presenta benissimo e ho ottimi ricordi dei giorni \u201cin blu\u201d trascorsi nella Formula\u00a01.<\/em><\/p>\n<\/blockquote>\n<blockquote>\n<p><strong>Guanyu Zhou:<\/strong> <em>Sono felicissimo di confermarmi pilota collaudatore del team, mentre mi appresto a cominciare il mio terzo anno come membro di Alpine Academy. \u00c8 la mia seconda stagione in questo ruolo, dopo essere stato pilota di sviluppo della scuderia nel 2019. Ci\u00f2 mi d\u00e0 l\u2019occasione di contribuire ai progressi del team. Si tratta di un\u2019esperienza estremamente preziosa lungo la strada per avvicinarmi alla F1. Questo ruolo mi permette di cercare di aiutare la scuderia ovunque sia possibile, su pista e al simulatore di Enstone. Il team mi d\u00e0 fiducia e voglio ringraziarlo contribuendo allo sviluppo dell\u2019auto per tutto l\u2019anno.<\/em><\/p>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":54998,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[6394,248,7853,293],"tags":[],"class_list":["post-54997","post","type-post","status-publish","format-standard","has-post-thumbnail","category-alpine","category-formula-1","category-motorsport","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ALPINE F1 TEAM LANCIA LA STAGIONE 2021 - AbmNews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.abmnews.com\/blog\/alpine-f1-team-lancia-la-stagione-2021\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ALPINE F1 TEAM LANCIA LA STAGIONE 2021 - AbmNews\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.abmnews.com\/blog\/alpine-f1-team-lancia-la-stagione-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"AbmNews\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ABMnews\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-03T07:48:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-03T07:48:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2021\/03\/unnamed-2-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"680\" \/>\n\t<meta property=\"og:image:height\" content=\"382\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:site\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alpine-f1-team-lancia-la-stagione-2021\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alpine-f1-team-lancia-la-stagione-2021\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\"},\"headline\":\"ALPINE F1 TEAM LANCIA LA STAGIONE 2021\",\"datePublished\":\"2021-03-03T07:48:42+00:00\",\"dateModified\":\"2021-03-03T07:48:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alpine-f1-team-lancia-la-stagione-2021\\\/\"},\"wordCount\":950,\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alpine-f1-team-lancia-la-stagione-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/unnamed-2-3.jpg\",\"articleSection\":[\"Alpine\",\"Formula 1\",\"Motorsport\",\"News\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alpine-f1-team-lancia-la-stagione-2021\\\/\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alpine-f1-team-lancia-la-stagione-2021\\\/\",\"name\":\"ALPINE F1 TEAM LANCIA LA STAGIONE 2021 - AbmNews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alpine-f1-team-lancia-la-stagione-2021\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alpine-f1-team-lancia-la-stagione-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/unnamed-2-3.jpg\",\"datePublished\":\"2021-03-03T07:48:42+00:00\",\"dateModified\":\"2021-03-03T07:48:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alpine-f1-team-lancia-la-stagione-2021\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alpine-f1-team-lancia-la-stagione-2021\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alpine-f1-team-lancia-la-stagione-2021\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/unnamed-2-3.jpg\",\"contentUrl\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/unnamed-2-3.jpg\",\"width\":680,\"height\":382},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alpine-f1-team-lancia-la-stagione-2021\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ALPINE F1 TEAM LANCIA LA STAGIONE 2021\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"name\":\"AbmNews\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\",\"name\":\"AbmNews\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"width\":544,\"height\":180,\"caption\":\"AbmNews\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ABMnews\",\"https:\\\/\\\/x.com\\\/ABMnewscom\",\"https:\\\/\\\/www.instagram.com\\\/abmnewsblog\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ALPINE F1 TEAM LANCIA LA STAGIONE 2021 - AbmNews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.abmnews.com\/blog\/alpine-f1-team-lancia-la-stagione-2021\/","og_locale":"it_IT","og_type":"article","og_title":"ALPINE F1 TEAM LANCIA LA STAGIONE 2021 - AbmNews","og_url":"https:\/\/www.abmnews.com\/blog\/alpine-f1-team-lancia-la-stagione-2021\/","og_site_name":"AbmNews","article_publisher":"https:\/\/www.facebook.com\/ABMnews","article_published_time":"2021-03-03T07:48:42+00:00","article_modified_time":"2021-03-03T07:48:44+00:00","og_image":[{"width":680,"height":382,"url":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2021\/03\/unnamed-2-3.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@ABMnewscom","twitter_site":"@ABMnewscom","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.abmnews.com\/blog\/alpine-f1-team-lancia-la-stagione-2021\/#article","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/alpine-f1-team-lancia-la-stagione-2021\/"},"author":{"name":"Redazione","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2"},"headline":"ALPINE F1 TEAM LANCIA LA STAGIONE 2021","datePublished":"2021-03-03T07:48:42+00:00","dateModified":"2021-03-03T07:48:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.abmnews.com\/blog\/alpine-f1-team-lancia-la-stagione-2021\/"},"wordCount":950,"publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/alpine-f1-team-lancia-la-stagione-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2021\/03\/unnamed-2-3.jpg","articleSection":["Alpine","Formula 1","Motorsport","News"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.abmnews.com\/blog\/alpine-f1-team-lancia-la-stagione-2021\/","url":"https:\/\/www.abmnews.com\/blog\/alpine-f1-team-lancia-la-stagione-2021\/","name":"ALPINE F1 TEAM LANCIA LA STAGIONE 2021 - AbmNews","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.abmnews.com\/blog\/alpine-f1-team-lancia-la-stagione-2021\/#primaryimage"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/alpine-f1-team-lancia-la-stagione-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2021\/03\/unnamed-2-3.jpg","datePublished":"2021-03-03T07:48:42+00:00","dateModified":"2021-03-03T07:48:44+00:00","breadcrumb":{"@id":"https:\/\/www.abmnews.com\/blog\/alpine-f1-team-lancia-la-stagione-2021\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.abmnews.com\/blog\/alpine-f1-team-lancia-la-stagione-2021\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/alpine-f1-team-lancia-la-stagione-2021\/#primaryimage","url":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2021\/03\/unnamed-2-3.jpg","contentUrl":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2021\/03\/unnamed-2-3.jpg","width":680,"height":382},{"@type":"BreadcrumbList","@id":"https:\/\/www.abmnews.com\/blog\/alpine-f1-team-lancia-la-stagione-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.abmnews.com\/blog\/"},{"@type":"ListItem","position":2,"name":"ALPINE F1 TEAM LANCIA LA STAGIONE 2021"}]},{"@type":"WebSite","@id":"https:\/\/www.abmnews.com\/blog\/#website","url":"https:\/\/www.abmnews.com\/blog\/","name":"AbmNews","description":"","publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.abmnews.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.abmnews.com\/blog\/#organization","name":"AbmNews","url":"https:\/\/www.abmnews.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","width":544,"height":180,"caption":"AbmNews"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ABMnews","https:\/\/x.com\/ABMnewscom","https:\/\/www.instagram.com\/abmnewsblog"]},{"@type":"Person","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.abmnews.com\/blog\/author\/redazione\/"}]}},"_links":{"self":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/54997","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/comments?post=54997"}],"version-history":[{"count":1,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/54997\/revisions"}],"predecessor-version":[{"id":54999,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/54997\/revisions\/54999"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media\/54998"}],"wp:attachment":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media?parent=54997"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/categories?post=54997"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/tags?post=54997"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}