{"id":57008,"date":"2021-04-27T14:01:56","date_gmt":"2021-04-27T12:01:56","guid":{"rendered":"http:\/\/www.abmnews.com\/blog\/?p=57008"},"modified":"2021-04-27T14:01:58","modified_gmt":"2021-04-27T12:01:58","slug":"alla-ricerca-delleccellenza-ds-7-crossback-e-il-mondo-dellartigianato-nel-golf","status":"publish","type":"post","link":"https:\/\/www.abmnews.com\/blog\/alla-ricerca-delleccellenza-ds-7-crossback-e-il-mondo-dellartigianato-nel-golf\/","title":{"rendered":"ALLA RICERCA DELL&#8217;ECCELLENZA: DS 7 CROSSBACK E IL MONDO DELL&#8217;ARTIGIANATO NEL GOLF"},"content":{"rendered":"\n<p class=\"rtejustify\">La partnership con la Federazione Italiana Golf \u00e8 appena iniziata, ma sono gi\u00e0 evidenti i differenti punti di contatto che hanno portato ad una collaborazione sorta quasi in maniera spontanea.<\/p>\n<p>\u00a0<\/p>\n<p class=\"rtejustify\">\u00c8 una evidente questione di valori e di stile, a rendere cos\u00ec naturale la sovrapposizione tra lo sport green per definizione ed il brand che pone il proprio raffinato savoir faire al servizio di ogni modello in gamma.<\/p>\n<p class=\"rtejustify\">Un\u2019esperienza che viene vissuta attraverso il parallelo con cui il \u2018Club Fitter\u2019 Emanuele Rodenghi realizza esclusivi ferri, in grado di soddisfare l\u2019uso individuale.<\/p>\n<p class=\"rtejustify\">Una prerogativa, quella del \u2018fatto su misura\u2019 che DS Automobiles ben conosce ed esprime grazie ad una capacit\u00e0 di personalizzazione che ha ben pochi rivali in campo automobilistico.<\/p>\n<p class=\"rtejustify\">Si tratta sempre di capacit\u00e0 artigianali, che distinguono l\u2019individuo dalla massa, conferendo quel tocco di unicit\u00e0 che si respira sul green di ogni campo da golf.<\/p>\n<p class=\"rtejustify\">Ed il colore verde del green, \u00e8 l\u2019ennesimo punto di contatto dei tecnologici modelli E-TENSE, con cui DS Automobiles da tempo dimostra una evidente propensione alla sostenibilit\u00e0 ambientale.<\/p>\n<p class=\"rtejustify\">I moderni SUV DS 3 CROSSBACK E-TENSE, 100% elettrico, e l\u2019ibrido plug-in DS 7 CROSSBACK E-TENSE sono oggi affiancati dalla lussuosa berlina DS 9 E-TENSE. Ennesima ibrida plug-in in grado di esprimere il valore zero di emissioni, rumore e vibrazioni, con cui favorire la concentrazione sui pi\u00f9 acclamati campi da golf della Penisola.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":57009,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[243,262,346],"tags":[],"class_list":["post-57008","post","type-post","status-publish","format-standard","has-post-thumbnail","category-ds","category-novita","category-video"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ALLA RICERCA DELL&#039;ECCELLENZA: DS 7 CROSSBACK E IL MONDO DELL&#039;ARTIGIANATO NEL GOLF - AbmNews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.abmnews.com\/blog\/alla-ricerca-delleccellenza-ds-7-crossback-e-il-mondo-dellartigianato-nel-golf\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ALLA RICERCA DELL&#039;ECCELLENZA: DS 7 CROSSBACK E IL MONDO DELL&#039;ARTIGIANATO NEL GOLF - AbmNews\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.abmnews.com\/blog\/alla-ricerca-delleccellenza-ds-7-crossback-e-il-mondo-dellartigianato-nel-golf\/\" \/>\n<meta property=\"og:site_name\" content=\"AbmNews\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ABMnews\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-27T12:01:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-27T12:01:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2021\/04\/ds3.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:site\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alla-ricerca-delleccellenza-ds-7-crossback-e-il-mondo-dellartigianato-nel-golf\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alla-ricerca-delleccellenza-ds-7-crossback-e-il-mondo-dellartigianato-nel-golf\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\"},\"headline\":\"ALLA RICERCA DELL&#8217;ECCELLENZA: DS 7 CROSSBACK E IL MONDO DELL&#8217;ARTIGIANATO NEL GOLF\",\"datePublished\":\"2021-04-27T12:01:56+00:00\",\"dateModified\":\"2021-04-27T12:01:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alla-ricerca-delleccellenza-ds-7-crossback-e-il-mondo-dellartigianato-nel-golf\\\/\"},\"wordCount\":237,\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alla-ricerca-delleccellenza-ds-7-crossback-e-il-mondo-dellartigianato-nel-golf\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/ds3.png\",\"articleSection\":[\"DS\",\"Novit\u00e0\",\"Video\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alla-ricerca-delleccellenza-ds-7-crossback-e-il-mondo-dellartigianato-nel-golf\\\/\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alla-ricerca-delleccellenza-ds-7-crossback-e-il-mondo-dellartigianato-nel-golf\\\/\",\"name\":\"ALLA RICERCA DELL'ECCELLENZA: DS 7 CROSSBACK E IL MONDO DELL'ARTIGIANATO NEL GOLF - AbmNews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alla-ricerca-delleccellenza-ds-7-crossback-e-il-mondo-dellartigianato-nel-golf\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alla-ricerca-delleccellenza-ds-7-crossback-e-il-mondo-dellartigianato-nel-golf\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/ds3.png\",\"datePublished\":\"2021-04-27T12:01:56+00:00\",\"dateModified\":\"2021-04-27T12:01:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alla-ricerca-delleccellenza-ds-7-crossback-e-il-mondo-dellartigianato-nel-golf\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alla-ricerca-delleccellenza-ds-7-crossback-e-il-mondo-dellartigianato-nel-golf\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alla-ricerca-delleccellenza-ds-7-crossback-e-il-mondo-dellartigianato-nel-golf\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/ds3.png\",\"contentUrl\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/ds3.png\",\"width\":800,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alla-ricerca-delleccellenza-ds-7-crossback-e-il-mondo-dellartigianato-nel-golf\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ALLA RICERCA DELL&#8217;ECCELLENZA: DS 7 CROSSBACK E IL MONDO DELL&#8217;ARTIGIANATO NEL GOLF\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"name\":\"AbmNews\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\",\"name\":\"AbmNews\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"width\":544,\"height\":180,\"caption\":\"AbmNews\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ABMnews\",\"https:\\\/\\\/x.com\\\/ABMnewscom\",\"https:\\\/\\\/www.instagram.com\\\/abmnewsblog\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ALLA RICERCA DELL'ECCELLENZA: DS 7 CROSSBACK E IL MONDO DELL'ARTIGIANATO NEL GOLF - AbmNews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.abmnews.com\/blog\/alla-ricerca-delleccellenza-ds-7-crossback-e-il-mondo-dellartigianato-nel-golf\/","og_locale":"it_IT","og_type":"article","og_title":"ALLA RICERCA DELL'ECCELLENZA: DS 7 CROSSBACK E IL MONDO DELL'ARTIGIANATO NEL GOLF - AbmNews","og_url":"https:\/\/www.abmnews.com\/blog\/alla-ricerca-delleccellenza-ds-7-crossback-e-il-mondo-dellartigianato-nel-golf\/","og_site_name":"AbmNews","article_publisher":"https:\/\/www.facebook.com\/ABMnews","article_published_time":"2021-04-27T12:01:56+00:00","article_modified_time":"2021-04-27T12:01:58+00:00","og_image":[{"width":800,"height":450,"url":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2021\/04\/ds3.png","type":"image\/png"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@ABMnewscom","twitter_site":"@ABMnewscom","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.abmnews.com\/blog\/alla-ricerca-delleccellenza-ds-7-crossback-e-il-mondo-dellartigianato-nel-golf\/#article","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/alla-ricerca-delleccellenza-ds-7-crossback-e-il-mondo-dellartigianato-nel-golf\/"},"author":{"name":"Redazione","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2"},"headline":"ALLA RICERCA DELL&#8217;ECCELLENZA: DS 7 CROSSBACK E IL MONDO DELL&#8217;ARTIGIANATO NEL GOLF","datePublished":"2021-04-27T12:01:56+00:00","dateModified":"2021-04-27T12:01:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.abmnews.com\/blog\/alla-ricerca-delleccellenza-ds-7-crossback-e-il-mondo-dellartigianato-nel-golf\/"},"wordCount":237,"publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/alla-ricerca-delleccellenza-ds-7-crossback-e-il-mondo-dellartigianato-nel-golf\/#primaryimage"},"thumbnailUrl":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2021\/04\/ds3.png","articleSection":["DS","Novit\u00e0","Video"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.abmnews.com\/blog\/alla-ricerca-delleccellenza-ds-7-crossback-e-il-mondo-dellartigianato-nel-golf\/","url":"https:\/\/www.abmnews.com\/blog\/alla-ricerca-delleccellenza-ds-7-crossback-e-il-mondo-dellartigianato-nel-golf\/","name":"ALLA RICERCA DELL'ECCELLENZA: DS 7 CROSSBACK E IL MONDO DELL'ARTIGIANATO NEL GOLF - AbmNews","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.abmnews.com\/blog\/alla-ricerca-delleccellenza-ds-7-crossback-e-il-mondo-dellartigianato-nel-golf\/#primaryimage"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/alla-ricerca-delleccellenza-ds-7-crossback-e-il-mondo-dellartigianato-nel-golf\/#primaryimage"},"thumbnailUrl":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2021\/04\/ds3.png","datePublished":"2021-04-27T12:01:56+00:00","dateModified":"2021-04-27T12:01:58+00:00","breadcrumb":{"@id":"https:\/\/www.abmnews.com\/blog\/alla-ricerca-delleccellenza-ds-7-crossback-e-il-mondo-dellartigianato-nel-golf\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.abmnews.com\/blog\/alla-ricerca-delleccellenza-ds-7-crossback-e-il-mondo-dellartigianato-nel-golf\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/alla-ricerca-delleccellenza-ds-7-crossback-e-il-mondo-dellartigianato-nel-golf\/#primaryimage","url":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2021\/04\/ds3.png","contentUrl":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2021\/04\/ds3.png","width":800,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/www.abmnews.com\/blog\/alla-ricerca-delleccellenza-ds-7-crossback-e-il-mondo-dellartigianato-nel-golf\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.abmnews.com\/blog\/"},{"@type":"ListItem","position":2,"name":"ALLA RICERCA DELL&#8217;ECCELLENZA: DS 7 CROSSBACK E IL MONDO DELL&#8217;ARTIGIANATO NEL GOLF"}]},{"@type":"WebSite","@id":"https:\/\/www.abmnews.com\/blog\/#website","url":"https:\/\/www.abmnews.com\/blog\/","name":"AbmNews","description":"","publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.abmnews.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.abmnews.com\/blog\/#organization","name":"AbmNews","url":"https:\/\/www.abmnews.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","width":544,"height":180,"caption":"AbmNews"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ABMnews","https:\/\/x.com\/ABMnewscom","https:\/\/www.instagram.com\/abmnewsblog"]},{"@type":"Person","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.abmnews.com\/blog\/author\/redazione\/"}]}},"_links":{"self":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/57008","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/comments?post=57008"}],"version-history":[{"count":1,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/57008\/revisions"}],"predecessor-version":[{"id":57010,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/57008\/revisions\/57010"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media\/57009"}],"wp:attachment":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media?parent=57008"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/categories?post=57008"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/tags?post=57008"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}