{"id":57727,"date":"2021-05-19T12:50:26","date_gmt":"2021-05-19T10:50:26","guid":{"rendered":"http:\/\/www.abmnews.com\/blog\/?p=57727"},"modified":"2021-05-19T12:50:28","modified_gmt":"2021-05-19T10:50:28","slug":"una-nuova-campagna-tutta-italiana-per-lofferta-dedicata-alla-gamma-suv-volkswagen","status":"publish","type":"post","link":"https:\/\/www.abmnews.com\/blog\/una-nuova-campagna-tutta-italiana-per-lofferta-dedicata-alla-gamma-suv-volkswagen\/","title":{"rendered":"Una nuova campagna tutta italiana per l\u2019offerta dedicata alla gamma SUV Volkswagen"},"content":{"rendered":"\n<p><strong>Se non la paghi, ti dimenticherai addirittura di averla acquistata. \u00c8 da questa iperbole creativa che nasce la nuova campagna di comunicazione della Volkswagen \u201cPer tre mesi dimenticherai di averla comprata\u201d; concepita e realizzata interamente in Italia, \u00e8 composta da inediti spot TV e radio che raccontano con ironia la pi\u00f9 recente iniziativa commerciale di Volkswagen Italia. L\u2019offerta prevede il rimborso delle prime tre rate della formula finanziaria Progetto Valore Volkswagen (PVV) per l\u2019acquisto dei modelli pi\u00f9 apprezzati della gamma SUV Volkswagen: T-Cross, T-Roc (anche Cabriolet) e Nuova Tiguan (esclusa eHYBRID). Il pubblico italiano potr\u00e0 conoscere maggiori dettagli di quest\u2019offerta e scoprire le novit\u00e0 della gamma SUV presso le Concessionarie Volkswagen, in occasione del Porte Aperte che si terr\u00e0 nella massima sicurezza durante il weekend di sabato 22 e domenica 23 maggio.<\/strong><\/p>\n<p>\u00a0<\/p>\n<p>\u201cPer tre mesi dimenticherai di averla comprata\u201d \u00e8 l\u2019ironico messaggio al centro della nuova campagna di comunicazione Volkswagen, concepita e realizzata interamente in Italia. Due inediti spot TV in onda su tutte le principali emittenti televisive nazionali da domenica 16 maggio, accompagnati da tre spot radio, promuovono l\u2019offerta dedicata ai modelli pi\u00f9 apprezzati della T-Family, la gamma di SUV e crossover della Volkswagen. L\u2019iniziativa commerciale \u201cLe prime tre rate le rimborsiamo noi\u201d prevede appunto il rimborso delle prime tre rate della formula finanziaria Progetto Valore Volkswagen (PVV) per chi sceglie i modelli T-Cross, T-Roc, T-Roc Cabriolet e Nuova Tiguan (esclusa eHYBRID). L\u2019iperbole creativa della campagna TV e radio si gioca sul contrasto tra l\u2019esperienza quotidiana, costellata di scadenze da ricordare, e la totale semplicit\u00e0 e leggerezza della soluzione offerta dalla Volkswagen che permette, per tre mesi, di dimenticarsi dei pagamenti e quindi anche di avere acquistato un nuovo SUV.<\/p>\n<p>\u00c8 proprio questo ci\u00f2 che succede ai protagonisti degli spot i quali, in situazioni diverse ma ugualmente paradossali, scoprono con stupore che l\u2019auto dei desideri \u00e8 gi\u00e0 in loro possesso. La produzione della campagna \u00e8 stata interamente realizzata dall\u2019ufficio italiano della Voltage, del Gruppo DDB, che ne ha declinato i contenuti per TV, radio, stampa, banner e social media.<\/p>\n<p>\u00a0<\/p>\n<p>I due spot TV della campagna di comunicazione sono disponibili ai seguenti indirizzi:<\/p>\n<p>Spot T-Roc: <a href=\"https:\/\/youtu.be\/CArSk5oKc6Q\">https:\/\/youtu.be\/CArSk5oKc6Q<\/a><\/p>\n<p>Spot Nuova Tiguan: <a href=\"https:\/\/youtu.be\/B9bro9xbZEM\">https:\/\/youtu.be\/B9bro9xbZEM<\/a><\/p>\n<p>\u00a0<\/p>\n<h1>L\u2019offerta \u201cLe prime tre rate le rimborsiamo noi\u201d<\/h1>\n<p>Dedicata ai modelli pi\u00f9 apprezzati della T-Family, la gamma SUV e crossover della Volkswagen, l\u2019iniziativa commerciale protagonista della nuova campagna di comunicazione italiana prevede il rimborso delle prime tre rate della formula finanziaria Progetto Valore Volkswagen (PVV) 36 mesi con TAN 4,99% o 6,49%. I Clienti che sceglieranno una Volkswagen T-Cross, una T-Roc (anche Cabriolet) o una Nuova Tiguan (esclusa eHYBRID), riceveranno il rimborso integrale delle prime tre rate mensili del PVV entro una settimana dall\u2019addebito.<\/p>\n<p>\u00a0<\/p>\n<p>Per esempio, con questa offerta basata sulla formula finanziaria Progetto Valore Volkswagen, sar\u00e0 possibile avere il City SUV Volkswagen T-Cross 1.0 TSI 95 CV Urban con un anticipo di 4.500 Euro e rate mensili da 139 Euro (TAN 4,99%, TAEG 6,40%). <br \/>Il crossover compatto T-Roc 1.0 TSI 110 CV Style \u00e8 proposto con un anticipo di <br \/>5.300 Euro e rate mensili da 169 Euro (TAN 4,99%, TAEG 6,18%), mentre per la variante T-Roc Cabriolet 1.5 TSI ACT 150 CV in allestimento Style l\u2019offerta prevede un anticipo di 5.800 Euro e rate mensili da 249 Euro (TAN 4,99%, TAEG 5,93%). Infine, per coloro che sceglieranno la Nuova Tiguan, il SUV Volkswagen aggiornato di recente nel design e nelle tecnologie di bordo, l\u2019offerta dedicata alla versione 1.5 TSI ACT 130 CV Life prevede un anticipo di 6.000 Euro e rate mensili da 249 Euro (TAN 4,99%, TAEG 5,97%). Per tutte queste iniziative promozionali, \u00e8 inclusa nel prezzo l\u2019estensione di garanzia Extra Time 2 anni o fino a 80.000 km.<\/p>\n<p>\u00a0<\/p>\n<p>Il pubblico italiano potr\u00e0 conoscere maggiori dettagli di quest\u2019offerta e scoprire le novit\u00e0 della gamma SUV presso le Concessionarie Volkswagen, in occasione del Porte Aperte che si terr\u00e0 nella massima sicurezza durante il weekend di sabato 22 e domenica 23 maggio.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":57728,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[6323,262,347],"tags":[],"class_list":["post-57727","post","type-post","status-publish","format-standard","has-post-thumbnail","category-mercato","category-novita","category-volkswagen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Una nuova campagna tutta italiana per l\u2019offerta dedicata alla gamma SUV Volkswagen - AbmNews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.abmnews.com\/blog\/una-nuova-campagna-tutta-italiana-per-lofferta-dedicata-alla-gamma-suv-volkswagen\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Una nuova campagna tutta italiana per l\u2019offerta dedicata alla gamma SUV Volkswagen - AbmNews\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.abmnews.com\/blog\/una-nuova-campagna-tutta-italiana-per-lofferta-dedicata-alla-gamma-suv-volkswagen\/\" \/>\n<meta property=\"og:site_name\" content=\"AbmNews\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ABMnews\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-19T10:50:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-19T10:50:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2021\/05\/unnamed-7-5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"499\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:site\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/una-nuova-campagna-tutta-italiana-per-lofferta-dedicata-alla-gamma-suv-volkswagen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/una-nuova-campagna-tutta-italiana-per-lofferta-dedicata-alla-gamma-suv-volkswagen\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\"},\"headline\":\"Una nuova campagna tutta italiana per l\u2019offerta dedicata alla gamma SUV Volkswagen\",\"datePublished\":\"2021-05-19T10:50:26+00:00\",\"dateModified\":\"2021-05-19T10:50:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/una-nuova-campagna-tutta-italiana-per-lofferta-dedicata-alla-gamma-suv-volkswagen\\\/\"},\"wordCount\":650,\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/una-nuova-campagna-tutta-italiana-per-lofferta-dedicata-alla-gamma-suv-volkswagen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/unnamed-7-5.jpg\",\"articleSection\":[\"Mercato\",\"Novit\u00e0\",\"Volkswagen\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/una-nuova-campagna-tutta-italiana-per-lofferta-dedicata-alla-gamma-suv-volkswagen\\\/\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/una-nuova-campagna-tutta-italiana-per-lofferta-dedicata-alla-gamma-suv-volkswagen\\\/\",\"name\":\"Una nuova campagna tutta italiana per l\u2019offerta dedicata alla gamma SUV Volkswagen - AbmNews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/una-nuova-campagna-tutta-italiana-per-lofferta-dedicata-alla-gamma-suv-volkswagen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/una-nuova-campagna-tutta-italiana-per-lofferta-dedicata-alla-gamma-suv-volkswagen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/unnamed-7-5.jpg\",\"datePublished\":\"2021-05-19T10:50:26+00:00\",\"dateModified\":\"2021-05-19T10:50:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/una-nuova-campagna-tutta-italiana-per-lofferta-dedicata-alla-gamma-suv-volkswagen\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/una-nuova-campagna-tutta-italiana-per-lofferta-dedicata-alla-gamma-suv-volkswagen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/una-nuova-campagna-tutta-italiana-per-lofferta-dedicata-alla-gamma-suv-volkswagen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/unnamed-7-5.jpg\",\"contentUrl\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/unnamed-7-5.jpg\",\"width\":800,\"height\":499},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/una-nuova-campagna-tutta-italiana-per-lofferta-dedicata-alla-gamma-suv-volkswagen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Una nuova campagna tutta italiana per l\u2019offerta dedicata alla gamma SUV Volkswagen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"name\":\"AbmNews\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\",\"name\":\"AbmNews\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"width\":544,\"height\":180,\"caption\":\"AbmNews\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ABMnews\",\"https:\\\/\\\/x.com\\\/ABMnewscom\",\"https:\\\/\\\/www.instagram.com\\\/abmnewsblog\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Una nuova campagna tutta italiana per l\u2019offerta dedicata alla gamma SUV Volkswagen - AbmNews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.abmnews.com\/blog\/una-nuova-campagna-tutta-italiana-per-lofferta-dedicata-alla-gamma-suv-volkswagen\/","og_locale":"it_IT","og_type":"article","og_title":"Una nuova campagna tutta italiana per l\u2019offerta dedicata alla gamma SUV Volkswagen - AbmNews","og_url":"https:\/\/www.abmnews.com\/blog\/una-nuova-campagna-tutta-italiana-per-lofferta-dedicata-alla-gamma-suv-volkswagen\/","og_site_name":"AbmNews","article_publisher":"https:\/\/www.facebook.com\/ABMnews","article_published_time":"2021-05-19T10:50:26+00:00","article_modified_time":"2021-05-19T10:50:28+00:00","og_image":[{"width":800,"height":499,"url":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2021\/05\/unnamed-7-5.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@ABMnewscom","twitter_site":"@ABMnewscom","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.abmnews.com\/blog\/una-nuova-campagna-tutta-italiana-per-lofferta-dedicata-alla-gamma-suv-volkswagen\/#article","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/una-nuova-campagna-tutta-italiana-per-lofferta-dedicata-alla-gamma-suv-volkswagen\/"},"author":{"name":"Redazione","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2"},"headline":"Una nuova campagna tutta italiana per l\u2019offerta dedicata alla gamma SUV Volkswagen","datePublished":"2021-05-19T10:50:26+00:00","dateModified":"2021-05-19T10:50:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.abmnews.com\/blog\/una-nuova-campagna-tutta-italiana-per-lofferta-dedicata-alla-gamma-suv-volkswagen\/"},"wordCount":650,"publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/una-nuova-campagna-tutta-italiana-per-lofferta-dedicata-alla-gamma-suv-volkswagen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2021\/05\/unnamed-7-5.jpg","articleSection":["Mercato","Novit\u00e0","Volkswagen"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.abmnews.com\/blog\/una-nuova-campagna-tutta-italiana-per-lofferta-dedicata-alla-gamma-suv-volkswagen\/","url":"https:\/\/www.abmnews.com\/blog\/una-nuova-campagna-tutta-italiana-per-lofferta-dedicata-alla-gamma-suv-volkswagen\/","name":"Una nuova campagna tutta italiana per l\u2019offerta dedicata alla gamma SUV Volkswagen - AbmNews","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.abmnews.com\/blog\/una-nuova-campagna-tutta-italiana-per-lofferta-dedicata-alla-gamma-suv-volkswagen\/#primaryimage"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/una-nuova-campagna-tutta-italiana-per-lofferta-dedicata-alla-gamma-suv-volkswagen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2021\/05\/unnamed-7-5.jpg","datePublished":"2021-05-19T10:50:26+00:00","dateModified":"2021-05-19T10:50:28+00:00","breadcrumb":{"@id":"https:\/\/www.abmnews.com\/blog\/una-nuova-campagna-tutta-italiana-per-lofferta-dedicata-alla-gamma-suv-volkswagen\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.abmnews.com\/blog\/una-nuova-campagna-tutta-italiana-per-lofferta-dedicata-alla-gamma-suv-volkswagen\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/una-nuova-campagna-tutta-italiana-per-lofferta-dedicata-alla-gamma-suv-volkswagen\/#primaryimage","url":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2021\/05\/unnamed-7-5.jpg","contentUrl":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2021\/05\/unnamed-7-5.jpg","width":800,"height":499},{"@type":"BreadcrumbList","@id":"https:\/\/www.abmnews.com\/blog\/una-nuova-campagna-tutta-italiana-per-lofferta-dedicata-alla-gamma-suv-volkswagen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.abmnews.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Una nuova campagna tutta italiana per l\u2019offerta dedicata alla gamma SUV Volkswagen"}]},{"@type":"WebSite","@id":"https:\/\/www.abmnews.com\/blog\/#website","url":"https:\/\/www.abmnews.com\/blog\/","name":"AbmNews","description":"","publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.abmnews.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.abmnews.com\/blog\/#organization","name":"AbmNews","url":"https:\/\/www.abmnews.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","width":544,"height":180,"caption":"AbmNews"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ABMnews","https:\/\/x.com\/ABMnewscom","https:\/\/www.instagram.com\/abmnewsblog"]},{"@type":"Person","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.abmnews.com\/blog\/author\/redazione\/"}]}},"_links":{"self":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/57727","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/comments?post=57727"}],"version-history":[{"count":1,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/57727\/revisions"}],"predecessor-version":[{"id":57729,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/57727\/revisions\/57729"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media\/57728"}],"wp:attachment":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media?parent=57727"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/categories?post=57727"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/tags?post=57727"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}